{"id":259,"date":"2024-10-04T17:12:34","date_gmt":"2024-10-04T17:12:34","guid":{"rendered":"https:\/\/cedric-u.com\/?post_type=portfolio&#038;p=259"},"modified":"2026-02-10T14:46:20","modified_gmt":"2026-02-10T14:46:20","slug":"cadillac-icon-unlocked","status":"publish","type":"portfolio","link":"https:\/\/cedric-u.com\/index.php\/portfolio\/cadillac-icon-unlocked\/","title":{"rendered":"Cadillac Icon Unlocked"},"content":{"rendered":"\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile media-centre-fixip\" style=\"grid-template-columns:auto 24%\"><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-align-right has-small-font-size\"><strong>POST-PRODUCTION :&nbsp;FIXIP<\/strong> \/ <strong>MIKA LAUJIN<\/strong><br><strong>CGI : FIXIP \/ CEDRIC UEBERSAX<\/strong><br><strong>CLIENT :&nbsp;FIXIP \/ CADILLAC<\/strong><br><strong>CREATIFS :&nbsp;FIXIP \/ THE LAB<\/strong><br><strong>PRODUCTEUR :&nbsp;<strong>FIXIP \/ THE LAB<\/strong><\/strong><\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"282\" src=\"http:\/\/cedric-u.com\/wp-content\/uploads\/2026\/02\/Fixip_logo_black.png\" alt=\"\" class=\"wp-image-140 size-full\" srcset=\"https:\/\/cedric-u.com\/wp-content\/uploads\/2026\/02\/Fixip_logo_black.png 1000w, https:\/\/cedric-u.com\/wp-content\/uploads\/2026\/02\/Fixip_logo_black-300x85.png 300w, https:\/\/cedric-u.com\/wp-content\/uploads\/2026\/02\/Fixip_logo_black-768x217.png 768w, https:\/\/cedric-u.com\/wp-content\/uploads\/2026\/02\/Fixip_logo_black-600x169.png 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" style=\"margin-top:var(--wp--preset--spacing--10);margin-bottom:var(--wp--preset--spacing--10)\"\/>\n\n\n\n<p><strong>Le projet Cadillac Icon Unlocked CGI \u00e9tait particuli\u00e8rement engageant.<\/strong>&nbsp;Initialement pr\u00e9vu comme un tournage simple de s\u00e9quences de running dans le d\u00e9sert, nos instincts cr\u00e9atifs ont rapidement pris le dessus, transformant le brief en quelque chose de beaucoup plus dynamique. Au lieu de nous en tenir au plan initial, nous avons repouss\u00e9 les limites en \u00e9levant le travail de la cam\u00e9ra, en am\u00e9liorant les d\u00e9tails de la voiture et en mettant l\u2019accent sur ses caract\u00e9ristiques cl\u00e9s afin de cr\u00e9er un r\u00e9cit visuellement percutant.<\/p>\n\n\n\n<p>L\u2019ensemble du projet a \u00e9t\u00e9 enti\u00e8rement r\u00e9alis\u00e9 sous Unreal Engine. Importation et rig complet du v\u00e9hicule, permettant un contr\u00f4le pr\u00e9cis de ses diff\u00e9rents \u00e9l\u00e9ments, ainsi que la cr\u00e9ation int\u00e9grale du d\u00e9cor. Une attention particuli\u00e8re a \u00e9galement \u00e9t\u00e9 port\u00e9e \u00e0 l\u2019ambiance, avec le d\u00e9veloppement de d\u00e9clinaisons climatiques incluant la pluie et la neige, afin d\u2019enrichir les conditions de mise en sc\u00e8ne et de renforcer l\u2019immersion.<\/p>\n\n\n\n<p>Ce qui a commenc\u00e9 comme un simple concept de s\u00e9quences de running s\u2019est transform\u00e9 en une vid\u00e9o de pr\u00e9sentation soign\u00e9e pour le mod\u00e8le. Ce projet a d\u00e9montr\u00e9 que m\u00eame dans des environnements apparemment simples, cr\u00e9ativit\u00e9 et exigence technique peuvent donner naissance \u00e0 quelque chose de remarquable. En affinant les mouvements de cam\u00e9ra, en exp\u00e9rimentant l\u2019\u00e9talonnage des couleurs et en travaillant minutieusement le montage, nous avons produit une s\u00e9quence courte mais visuellement marquante.<\/p>\n\n\n\n<p> Ce projet illustre comment les marques peuvent explorer une communication rapide, cr\u00e9ative et percutante, en proposant des visuels m\u00e9morables m\u00eame dans des formats compacts. Une r\u00e9alisation particuli\u00e8rement satisfaisante, mettant en lumi\u00e8re la valeur de la cr\u00e9ativit\u00e9 et de la ma\u00eetrise technique \u00e0 chaque \u00e9tape.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>POST-PRODUCTION :&nbsp;FIXIP \/ MIKA LAUJINCGI : FIXIP \/ CEDRIC UEBERSAXCLIENT :&nbsp;FIXIP \/ CADILLACCREATIFS :&nbsp;FIXIP \/ THE LABPRODUCTEUR :&nbsp;FIXIP \/ THE LAB Le projet Cadillac Icon Unlocked CGI \u00e9tait particuli\u00e8rement engageant.&nbsp;Initialement pr\u00e9vu comme un tournage simple de s\u00e9quences de running dans le d\u00e9sert, nos instincts cr\u00e9atifs ont rapidement pris le dessus, transformant le brief en quelque&hellip;<\/p>\n","protected":false},"author":2,"featured_media":275,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[3,6],"portfolio_tag":[12],"class_list":["post-259","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-3d","portfolio_category-video","portfolio_tag-book"],"acf":[],"_links":{"self":[{"href":"https:\/\/cedric-u.com\/index.php\/wp-json\/wp\/v2\/portfolio\/259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cedric-u.com\/index.php\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/cedric-u.com\/index.php\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/cedric-u.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cedric-u.com\/index.php\/wp-json\/wp\/v2\/comments?post=259"}],"version-history":[{"count":5,"href":"https:\/\/cedric-u.com\/index.php\/wp-json\/wp\/v2\/portfolio\/259\/revisions"}],"predecessor-version":[{"id":1017,"href":"https:\/\/cedric-u.com\/index.php\/wp-json\/wp\/v2\/portfolio\/259\/revisions\/1017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cedric-u.com\/index.php\/wp-json\/wp\/v2\/media\/275"}],"wp:attachment":[{"href":"https:\/\/cedric-u.com\/index.php\/wp-json\/wp\/v2\/media?parent=259"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/cedric-u.com\/index.php\/wp-json\/wp\/v2\/portfolio_category?post=259"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/cedric-u.com\/index.php\/wp-json\/wp\/v2\/portfolio_tag?post=259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}